{"id":18,"date":"2011-09-08T12:50:56","date_gmt":"2011-09-08T16:50:56","guid":{"rendered":"http:\/\/www.nhvweb.net\/templatedepanhhs\/?page_id=18"},"modified":"2024-01-18T18:04:32","modified_gmt":"2024-01-18T18:04:32","slug":"courses","status":"publish","type":"page","link":"https:\/\/www.nhvweb.net\/nhhs\/music\/courses\/","title":{"rendered":"Courses"},"content":{"rendered":"<div align=\"center\">\n<p style=\"text-align: left\">Click\u00a0<strong><a href=\"https:\/\/www.nhvweb.net\/nhhs\/home\/course-scheduling-information-for-2024-2025\/\">HERE<\/a><\/strong> to refer to the current Course Selection info sent out by NHHS Guidance Dept. It is also available <a href=\"https:\/\/docs.google.com\/document\/d\/1IGGpf6Ys7Ik1lNTy3hgY9B2f7WN455jBxTe12j0KJJ0\/edit?usp=sharing\">HERE<\/a>.<\/p>\n<table style=\"height: 1587px;width: 100%;border-style: solid\" border=\"0\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr style=\"height: 68px\">\n<td style=\"width: 21.3095%;height: 91px\" rowspan=\"2\" valign=\"top\">\n<p align=\"center\"><b>Course Number<\/b><\/p>\n<\/td>\n<td style=\"width: 41.3095%;height: 91px\" rowspan=\"2\" valign=\"top\">\n<p align=\"center\"><b>Course Name<\/b><\/p>\n<\/td>\n<td style=\"width: 10.8333%;height: 68px\" colspan=\"4\" valign=\"top\">\n<p align=\"center\"><b>Grade<\/b><\/p>\n<\/td>\n<td style=\"width: 14.1667%;height: 91px\" rowspan=\"2\" valign=\"top\">\n<p align=\"center\"><b>Credits<\/b><\/p>\n<\/td>\n<td style=\"width: 12.0238%;height: 91px\" rowspan=\"2\" valign=\"top\">\n<p align=\"center\"><b>Duration<\/b><\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 23px\">\n<td style=\"width: 1.90476%;height: 23px\" valign=\"top\"><b>9<\/b><\/td>\n<td style=\"width: 3.09524%;height: 23px\" valign=\"top\"><b>10<\/b><\/td>\n<td style=\"width: 2.7381%;height: 23px\" valign=\"top\"><b>11<\/b><\/td>\n<td style=\"width: 3.09524%;height: 23px\" valign=\"top\"><b>12<\/b><\/td>\n<\/tr>\n<tr style=\"height: 68px\">\n<td style=\"width: 21.3095%;height: 68px\">\n<p align=\"center\">580<\/p>\n<\/td>\n<td style=\"width: 41.3095%;height: 68px\">\n<p align=\"center\">History of Rock &amp; Roll<\/p>\n<\/td>\n<td style=\"width: 1.90476%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 3.09524%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 2.7381%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 3.09524%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 14.1667%;height: 68px\">\n<p align=\"center\">2.5 cr.<\/p>\n<\/td>\n<td style=\"width: 12.0238%;height: 68px\">\n<p align=\"center\">18 wks.<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 68px\">\n<td style=\"width: 21.3095%;height: 68px\">\n<p align=\"center\">588<\/p>\n<\/td>\n<td style=\"width: 41.3095%;height: 68px\">\n<p align=\"center\">Electronic Music 1<\/p>\n<\/td>\n<td style=\"width: 1.90476%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 3.09524%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 2.7381%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 3.09524%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 14.1667%;height: 68px\">\n<p align=\"center\">2.5 cr.<\/p>\n<\/td>\n<td style=\"width: 12.0238%;height: 68px\">\n<p align=\"center\">18 wks.<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 68px\">\n<td style=\"width: 21.3095%;height: 68px\">\n<p align=\"center\">589<\/p>\n<\/td>\n<td style=\"width: 41.3095%;height: 68px\">\n<p align=\"center\">Electronic Music 2<\/p>\n<\/td>\n<td style=\"width: 1.90476%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 3.09524%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 2.7381%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 3.09524%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 14.1667%;height: 68px\">\n<p align=\"center\">2.5 cr.<\/p>\n<\/td>\n<td style=\"width: 12.0238%;height: 68px\">\n<p align=\"center\">18 wks.<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 68px\">\n<td style=\"width: 21.3095%;height: 68px\">\n<p align=\"center\">593<\/p>\n<\/td>\n<td style=\"width: 41.3095%;height: 68px\">\n<p align=\"center\">Electronic Music 3<\/p>\n<\/td>\n<td style=\"width: 1.90476%;height: 68px\" valign=\"top\">\n<p align=\"center\">\n<\/td>\n<td style=\"width: 3.09524%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 2.7381%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 3.09524%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 14.1667%;height: 68px\">\n<p align=\"center\">5 cr.<\/p>\n<\/td>\n<td style=\"width: 12.0238%;height: 68px\">\n<p align=\"center\">36 wks.<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 68px\">\n<td style=\"width: 21.3095%;height: 68px\">\n<p align=\"center\">590<\/p>\n<\/td>\n<td style=\"width: 41.3095%;height: 68px\">\n<p align=\"center\">Band<\/p>\n<\/td>\n<td style=\"width: 1.90476%;height: 68px\" valign=\"top\">\n<p align=\"center\">\n<\/td>\n<td style=\"width: 3.09524%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 2.7381%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 3.09524%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 14.1667%;height: 68px\">\n<p align=\"center\">5 cr.<\/p>\n<\/td>\n<td style=\"width: 12.0238%;height: 68px\">\n<p align=\"center\">36 wks.<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 68px\">\n<td style=\"width: 21.3095%;height: 68px\">\n<p align=\"center\">591<\/p>\n<\/td>\n<td style=\"width: 41.3095%;height: 68px\">\n<p align=\"center\">Freshman Band<\/p>\n<\/td>\n<td style=\"width: 1.90476%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 3.09524%;height: 68px\" valign=\"top\">\n<p align=\"center\">\n<\/td>\n<td style=\"width: 2.7381%;height: 68px\" valign=\"top\">\n<p align=\"center\">\n<\/td>\n<td style=\"width: 3.09524%;height: 68px\" valign=\"top\">\n<p align=\"center\">\n<\/td>\n<td style=\"width: 14.1667%;height: 68px\">\n<p align=\"center\">5 cr.<\/p>\n<\/td>\n<td style=\"width: 12.0238%;height: 68px\">\n<p align=\"center\">36 wks.<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 68px\">\n<td style=\"width: 21.3095%;height: 68px\">\n<p align=\"center\">592<\/p>\n<\/td>\n<td style=\"width: 41.3095%;height: 68px\">\n<p align=\"center\">String Ensemble<\/p>\n<\/td>\n<td style=\"width: 1.90476%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 3.09524%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 2.7381%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 3.09524%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 14.1667%;height: 68px\">\n<p align=\"center\">5 cr.<\/p>\n<\/td>\n<td style=\"width: 12.0238%;height: 68px\">\n<p align=\"center\">36 wks.<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 68px\">\n<td style=\"width: 21.3095%;height: 68px\">\n<p align=\"center\">599<\/p>\n<\/td>\n<td style=\"width: 41.3095%;height: 68px\">\n<p align=\"center\">Jazz Ensemble<\/p>\n<\/td>\n<td style=\"width: 1.90476%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 3.09524%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 2.7381%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 3.09524%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 14.1667%;height: 68px\">\n<p align=\"center\">2.5 cr<\/p>\n<\/td>\n<td style=\"width: 12.0238%;height: 68px\">\n<p align=\"center\">36 wks.<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 68px\">\n<td style=\"width: 21.3095%;height: 68px\">\n<p align=\"center\">600<\/p>\n<\/td>\n<td style=\"width: 41.3095%;height: 68px\">\n<p align=\"center\">Beginning Instrumental Lessons<\/p>\n<\/td>\n<td style=\"width: 1.90476%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 3.09524%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 2.7381%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 3.09524%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 14.1667%;height: 68px\">\n<p align=\"center\">1 cr.<\/p>\n<\/td>\n<td style=\"width: 12.0238%;height: 68px\">\n<p align=\"center\">36 wks.<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 68px\">\n<td style=\"width: 21.3095%;height: 68px\">\n<p align=\"center\">601<\/p>\n<\/td>\n<td style=\"width: 41.3095%;height: 68px\">\n<p align=\"center\">Advanced Instrumental Lessons<\/p>\n<\/td>\n<td style=\"width: 1.90476%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 3.09524%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 2.7381%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 3.09524%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 14.1667%;height: 68px\">\n<p align=\"center\">1 cr.<\/p>\n<\/td>\n<td style=\"width: 12.0238%;height: 68px\">\n<p align=\"center\">36 wks.<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 68px\">\n<td style=\"width: 21.3095%;height: 68px\">\n<p align=\"center\">609<\/p>\n<\/td>\n<td style=\"width: 41.3095%;height: 68px\">\n<p align=\"center\">Voice Lessons<\/p>\n<\/td>\n<td style=\"width: 1.90476%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 3.09524%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 2.7381%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 3.09524%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 14.1667%;height: 68px\">\n<p align=\"center\">1 cr.<\/p>\n<\/td>\n<td style=\"width: 12.0238%;height: 68px\">\n<p align=\"center\">36 wks.<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 68px\">\n<td style=\"width: 21.3095%;height: 68px\">\n<p align=\"center\">610<\/p>\n<\/td>\n<td style=\"width: 41.3095%;height: 68px\">\n<p align=\"center\">Concert Choir<\/p>\n<\/td>\n<td style=\"width: 1.90476%;height: 68px\" valign=\"top\">\n<p align=\"center\">\n<\/td>\n<td style=\"width: 3.09524%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 2.7381%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 3.09524%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 14.1667%;height: 68px\">\n<p align=\"center\">5 cr.<\/p>\n<\/td>\n<td style=\"width: 12.0238%;height: 68px\">\n<p align=\"center\">36 wks.<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 68px\">\n<td style=\"width: 21.3095%;height: 68px\">\n<p align=\"center\">611<\/p>\n<\/td>\n<td style=\"width: 41.3095%;height: 68px\">\n<p align=\"center\">Freshman Choir<\/p>\n<\/td>\n<td style=\"width: 1.90476%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 3.09524%;height: 68px\" valign=\"top\">\n<p align=\"center\">\n<\/td>\n<td style=\"width: 2.7381%;height: 68px\" valign=\"top\">\n<p align=\"center\">\n<\/td>\n<td style=\"width: 3.09524%;height: 68px\" valign=\"top\">\n<p align=\"center\">\n<\/td>\n<td style=\"width: 14.1667%;height: 68px\">\n<p align=\"center\">5 cr.<\/p>\n<\/td>\n<td style=\"width: 12.0238%;height: 68px\">\n<p align=\"center\">36 wks.<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 68px\">\n<td style=\"width: 21.3095%;height: 68px\">\n<p align=\"center\">614<\/p>\n<\/td>\n<td style=\"width: 41.3095%;height: 68px\">\n<p align=\"center\">Composition and Arranging (Electronic Music III)<\/p>\n<\/td>\n<td style=\"width: 1.90476%;height: 68px\" valign=\"top\">\n<p align=\"center\">\n<\/td>\n<td style=\"width: 3.09524%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 2.7381%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 3.09524%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 14.1667%;height: 68px\">\n<p align=\"center\">2.5 cr.<\/p>\n<\/td>\n<td style=\"width: 12.0238%;height: 68px\">\n<p align=\"center\">18 wks.<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 68px\">\n<td style=\"width: 21.3095%;height: 68px\">\n<p align=\"center\">615<\/p>\n<\/td>\n<td style=\"width: 41.3095%;height: 68px\">\n<p align=\"center\">Show Choir<\/p>\n<\/td>\n<td style=\"width: 1.90476%;height: 68px\" valign=\"top\">\n<p align=\"center\">\n<\/td>\n<td style=\"width: 3.09524%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 2.7381%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 3.09524%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 14.1667%;height: 68px\">\n<p align=\"center\">2.5 cr.<\/p>\n<\/td>\n<td style=\"width: 12.0238%;height: 68px\">\n<p align=\"center\">36 wks.<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 68px\">\n<td style=\"width: 21.3095%;height: 68px\">\n<p align=\"center\">612<\/p>\n<\/td>\n<td style=\"width: 41.3095%;height: 68px\">\n<p align=\"center\">Chamber Choir<\/p>\n<\/td>\n<td style=\"width: 1.90476%;height: 68px\" valign=\"top\">\n<p align=\"center\">\n<\/td>\n<td style=\"width: 3.09524%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 2.7381%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 3.09524%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 14.1667%;height: 68px\">\n<p align=\"center\">2.5 cr.<\/p>\n<\/td>\n<td style=\"width: 12.0238%;height: 68px\">\n<p align=\"center\">36 wks<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 68px\">\n<td style=\"width: 21.3095%;height: 68px\">\n<p align=\"center\">616<\/p>\n<\/td>\n<td style=\"width: 41.3095%;height: 68px\">\n<p align=\"center\">Madrigal Singers<\/p>\n<\/td>\n<td style=\"width: 1.90476%;height: 68px\" valign=\"top\">\n<p align=\"center\">\n<\/td>\n<td style=\"width: 3.09524%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 2.7381%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 3.09524%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 14.1667%;height: 68px\">\n<p align=\"center\">2.5 cr.<\/p>\n<\/td>\n<td style=\"width: 12.0238%;height: 68px\">\n<p align=\"center\">36 wks<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 68px\">\n<td style=\"width: 21.3095%;height: 68px\">\n<p align=\"center\">585<\/p>\n<\/td>\n<td style=\"width: 41.3095%;height: 68px\">\n<p align=\"center\">Music Theory<\/p>\n<\/td>\n<td style=\"width: 1.90476%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 3.09524%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 2.7381%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 3.09524%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 14.1667%;height: 68px\">\n<p align=\"center\">2.5 cr.<\/p>\n<\/td>\n<td style=\"width: 12.0238%;height: 68px\">\n<p align=\"center\">18 wks.<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 68px\">\n<td style=\"width: 21.3095%;height: 68px\">\n<p align=\"center\">617<\/p>\n<\/td>\n<td style=\"width: 41.3095%;height: 68px\">\n<p align=\"center\">AP Music Theory<\/p>\n<\/td>\n<td style=\"width: 1.90476%;height: 68px\" valign=\"top\">\n<p align=\"center\">\n<\/td>\n<td style=\"width: 3.09524%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 2.7381%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 3.09524%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 14.1667%;height: 68px\">\n<p align=\"center\">5 cr. H\/Wt.<\/p>\n<\/td>\n<td style=\"width: 12.0238%;height: 68px\">\n<p align=\"center\">36 wks.<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 68px\">\n<td style=\"width: 21.3095%;height: 68px\">\n<p align=\"center\">614<\/p>\n<\/td>\n<td style=\"width: 41.3095%;height: 68px\">\n<p align=\"center\">Composition and Arranging<\/p>\n<\/td>\n<td style=\"width: 1.90476%;height: 68px\" valign=\"top\">\n<p align=\"center\">\n<\/td>\n<td style=\"width: 3.09524%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 2.7381%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 3.09524%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 14.1667%;height: 68px\">\n<p align=\"center\">2.5 cr.<\/p>\n<\/td>\n<td style=\"width: 12.0238%;height: 68px\">\n<p align=\"center\">18 wks.<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 68px\">\n<td style=\"width: 21.3095%;height: 68px\">\n<p align=\"center\">618<\/p>\n<\/td>\n<td style=\"width: 41.3095%;height: 68px\">\n<p align=\"center\">Beginning Guitar<\/p>\n<\/td>\n<td style=\"width: 1.90476%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 3.09524%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 2.7381%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 3.09524%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 14.1667%;height: 68px\">\n<p align=\"center\">2.5 cr.<\/p>\n<\/td>\n<td style=\"width: 12.0238%;height: 68px\">\n<p align=\"center\">18 wks.<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 68px\">\n<td style=\"width: 21.3095%;height: 68px\">\n<p align=\"center\">619<\/p>\n<\/td>\n<td style=\"width: 41.3095%;height: 68px\">\n<p align=\"center\">Guitar II<\/p>\n<\/td>\n<td style=\"width: 1.90476%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 3.09524%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 2.7381%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 3.09524%;height: 68px\" valign=\"top\">\n<p align=\"center\">x<\/p>\n<\/td>\n<td style=\"width: 14.1667%;height: 68px\">\n<p align=\"center\">2.5 cr.<\/p>\n<\/td>\n<td style=\"width: 12.0238%;height: 68px\">\n<p align=\"center\">18 wks.<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Click\u00a0HERE to refer to the current Course Selection info sent out by NHHS Guidance Dept. It is also available HERE. Course Number Course Name Grade Credits Duration 9 10 11 12 580 History of Rock &amp; Roll x x x x 2.5 cr. 18 wks. 588 Electronic Music 1 x x x x 2.5 cr. [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-18","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-09-09 06:46:54","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.nhvweb.net\/nhhs\/music\/wp-json\/wp\/v2\/pages\/18","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nhvweb.net\/nhhs\/music\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.nhvweb.net\/nhhs\/music\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.nhvweb.net\/nhhs\/music\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nhvweb.net\/nhhs\/music\/wp-json\/wp\/v2\/comments?post=18"}],"version-history":[{"count":10,"href":"https:\/\/www.nhvweb.net\/nhhs\/music\/wp-json\/wp\/v2\/pages\/18\/revisions"}],"predecessor-version":[{"id":859,"href":"https:\/\/www.nhvweb.net\/nhhs\/music\/wp-json\/wp\/v2\/pages\/18\/revisions\/859"}],"wp:attachment":[{"href":"https:\/\/www.nhvweb.net\/nhhs\/music\/wp-json\/wp\/v2\/media?parent=18"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}